{"id":25,"date":"2022-09-14T12:11:41","date_gmt":"2022-09-14T10:11:41","guid":{"rendered":"https:\/\/dolinawiedzy.pl\/kalisz\/?page_id=25"},"modified":"2025-05-06T10:47:02","modified_gmt":"2025-05-06T08:47:02","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/dolinawiedzy.pl\/kalisz\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">ADRES<\/h2>\n\n\n\n<div id=\"section-ge7d1fd\" class=\"wp-block-gutentor-e0 section-ge7d1fd gutentor-element gutentor-element-advanced-text\"><div class=\"gutentor-text-wrap\"><p class=\"gutentor-text\">Instytut In\u017cynierii Mechanicznej<br \/>ul. Pozna\u0144ska 201-205, 62-800 Kalisz<\/p><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Telefon<\/h2>\n\n\n\n<p>Koordynator Biura Filii &#8211; Kinga Balcerzyk-Jeziorska<\/p>\n\n\n\n<div id=\"section-g8d91b4\" class=\"wp-block-gutentor-e0 section-g8d91b4 gutentor-element gutentor-element-advanced-text\"><div class=\"gutentor-text-wrap\"><p class=\"gutentor-text\"><a href=\"tel:+48607082477\">+48 607 082 477<\/a><\/p><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">E-mail<\/h2>\n\n\n\n<p>kinga.balcerzyk@dolinawiedzy.pl<\/p>\n\n\n\n<div id=\"section-gbcfea5\" class=\"wp-block-gutentor-e0 section-gbcfea5 gutentor-element gutentor-element-advanced-text\"><div class=\"gutentor-text-wrap\"><p class=\"gutentor-text\"><a href=\"mailto:kalisz@dolinawiedzy.pl\">kalisz@dolinawiedzy.pl<\/a><\/p><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Formularz kontaktowy<\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f64-o1\" lang=\"pl-PL\" dir=\"ltr\" data-wpcf7-id=\"64\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/kalisz\/wp-json\/wp\/v2\/pages\/25#wpcf7-f64-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formularz kontaktowy\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"64\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pl_PL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f64-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-sm-12 col-md-3\">\n\t\t<div class=\"form-group\">\n\t\t\t<p><label for=\"name\">Imi\u0119 i nazwisko:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-sm-12 col-md-3\">\n\t\t<div class=\"form-group\">\n\t\t\t<p><label for=\"email\">E-mail:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-sm-12 col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<p><label for=\"subject\">Temat:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"subject\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-sm-12 col-md-12\">\n\t\t<div class=\"form-group your-message\">\n\t\t\t<p><label for=\"message\">Wiadomo\u015b\u0107:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"8\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"message\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-sm-12 col-md-4\">\n\t\t<p><input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"2724168381\" \/><img decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1 w-25 form-control-lg lazyload\" width=\"84\" height=\"28\" alt=\"captcha\" data-src=\"https:\/\/dolinawiedzy.pl\/kalisz\/wp-content\/uploads\/sites\/10\/wpcf7_captcha\/2724168381.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 84px; --smush-placeholder-aspect-ratio: 84\/28;\" \/><br \/>\nPrzepisz kod z obrazka<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"4\" maxlength=\"4\" class=\"wpcf7-form-control wpcf7-captchar w-25\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-sm-12 col-md-4\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" value=\"Wy\u015blij\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ADRES Telefon Koordynator Biura Filii &#8211; Kinga Balcerzyk-Jeziorska E-mail kinga.balcerzyk@dolinawiedzy.pl Formularz kontaktowy<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":10,"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":517,"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/pages\/25\/revisions\/517"}],"wp:attachment":[{"href":"https:\/\/dolinawiedzy.pl\/kalisz\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}